{"id":16444,"date":"2021-08-04T22:43:45","date_gmt":"2021-08-05T01:43:45","guid":{"rendered":"https:\/\/soloweb.com.br\/blog\/?p=16444"},"modified":"2021-08-04T22:43:45","modified_gmt":"2021-08-05T01:43:45","slug":"iniciar-pwas-automaticamente-no-login-do-sistema-operacional","status":"publish","type":"post","link":"https:\/\/soloweb.com.br\/blog\/2021\/08\/04\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\/","title":{"rendered":"Iniciar PWAs automaticamente ap\u00f3s login do Sistema Operacional"},"content":{"rendered":"<p>Inicie aplica\u00e7\u00f5es PWA ou Progressive Web App automaticamente ap\u00f3s realizar login no Sistema Operacional. Essa capacidade est\u00e1 dispon\u00edvel em muitos sistemas operacionais h\u00e1 muito tempo, mas foi reservada para aplicativos espec\u00edficos da plataforma.\u00a0Agora tamb\u00e9m est\u00e1 dispon\u00edvel para Web Apps.<\/p>\n<p>Progressive Web App (PWA) \u00e9 um termo usado para denotar uma nova metodologia de desenvolvimento de software. Ao contr\u00e1rio dos tradicionais aplicativos, um Progressive Web App pode ser visto como uma evolu\u00e7\u00e3o h\u00edbrida entre as p\u00e1ginas da web regulares (ou sites) e um aplicativo m\u00f3vel. Este novo modelo de aplica\u00e7\u00e3o combina recursos oferecidos pelos mais modernos navegadores, com as vantagens de uso de um celular. (wikipedia.org)<\/p>\n<p>E caso deseje ter ou converter seu site para uma PWA, entre em contato conosco, desenvolvemos solu\u00e7\u00f5es personalizadas, sites, sistemas, lojas virtuais e muito mais, al\u00e9m de oferecer os melhores servidores dedicados e VPS com o menor pre\u00e7o do Brasil. Acesse: <a href=\"https:\/\/soloweb.com.br\">www.soloweb.com.br<\/a><\/p>\n<p>Op\u00e7\u00e3o para visualizar em formato de v\u00eddeo<\/p>\n<p><iframe loading=\"lazy\" title=\"Iniciar PWAs automaticamente ap\u00f3s login do Sistema Operacional\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/xqWC3TqyOmM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Vamos a dica:<\/p>\n<h2 id=\"save-users-time\">Economize tempo dos usu\u00e1rios<\/h2>\n<p>Os usu\u00e1rios que desejam executar automaticamente um conjunto de aplicativos que sempre usam. Um exemplo t\u00edpico s\u00e3o os aplicativos de alto envolvimento, como clientes de e-mail, aplicativos de bate-papo, pain\u00e9is de monitoramento e aplicativos de exibi\u00e7\u00e3o de dados em tempo real, e outros.<\/p>\n<p>A inicializa\u00e7\u00e3o autom\u00e1tica desses aplicativos no login agiliza a experi\u00eancia do usu\u00e1rio, evitando que os usu\u00e1rios tenham que encontrar esses aplicativos para inici\u00e1-los nos menus. Tamb\u00e9m \u00e9 \u00fatil para executar a\u00e7\u00f5es autom\u00e1ticas de rotina.<\/p>\n<h2 id=\"add-a-pwa-to-run-on-login\">Primeiro vamos instalar algum PWA<\/h2>\n<p>Em nosso exemplo vamos instalar o pr\u00f3prio site da <a href=\"https:\/\/soloweb.com.br\">SoloWeb<\/a> ( <a href=\"https:\/\/soloweb.com.br\">www.soloweb.com.br<\/a> ), mas isso pode ser feito com qualquer outro que possua esta tecnologia.<\/p>\n<p>Para identificar que o website \u00e9 um PWA verifique se possui este \u00edcone que permite sua instala\u00e7\u00e3o.<\/p>\n<h2 id=\"add-a-pwa-to-run-on-login\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16446 size-full\" src=\"https:\/\/soloweb.com.br\/blog1\/wp-content\/uploads\/2021\/08\/00000001.png\" alt=\"\" width=\"348\" height=\"218\" srcset=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/00000001.png 348w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/00000001-300x188.png 300w\" sizes=\"auto, (max-width: 348px) 100vw, 348px\" \/><\/h2>\n<p>Clique neste \u00edcone e em seguida clique em &#8221; Instalar &#8221;<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16447 size-full\" src=\"https:\/\/soloweb.com.br\/blog1\/wp-content\/uploads\/2021\/08\/00000001-1.png\" alt=\"\" width=\"522\" height=\"287\" srcset=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/00000001-1.png 522w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/00000001-1-300x165.png 300w\" sizes=\"auto, (max-width: 522px) 100vw, 522px\" \/><\/h2>\n<p>Uma outra op\u00e7\u00e3o \u00e9 acessar o menu do navegador e verificar se est\u00e1 dispon\u00edvel a op\u00e7\u00e3o &#8221; Instalar NOME_DO_APP &#8221; se esta op\u00e7\u00e3o n\u00e3o estiver dispon\u00edvel \u00e9 porque este site n\u00e3o est\u00e1 com as conformidades da PWAs<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16448 size-full\" src=\"https:\/\/soloweb.com.br\/blog1\/wp-content\/uploads\/2021\/08\/00000001-2.png\" alt=\"\" width=\"476\" height=\"378\" srcset=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/00000001-2.png 476w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/00000001-2-300x238.png 300w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/h2>\n<p>Ap\u00f3s a instala\u00e7\u00e3o que por sinal \u00e9 muito r\u00e1pido um \u00edcone que representa o app estar\u00e1 dispon\u00edvel na sua \u00e1rea de trabalho<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16449 size-full\" src=\"https:\/\/soloweb.com.br\/blog1\/wp-content\/uploads\/2021\/08\/Capturar.jpg\" alt=\"\" width=\"441\" height=\"182\" srcset=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/Capturar.jpg 441w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/Capturar-300x124.jpg 300w\" sizes=\"auto, (max-width: 441px) 100vw, 441px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2>Pronto com o PWA devidamente instalado agora vamos adicion\u00e1-lo para executar ap\u00f3s login<\/h2>\n<p>Dispon\u00edvel a partir do Chrome 91 ou Edge 91 ou posterior, no Windows, Linux e MacOS.<\/p>\n<p>Para configurar um aplicativo para ser executado no login, digite no navegador:<\/p>\n<pre class=\"lang:default decode:true\">about:\/\/apps<\/pre>\n<p>Ser\u00e1 exibido todos os Apps WAP instalados em seu computador<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16450 size-full\" src=\"https:\/\/soloweb.com.br\/blog1\/wp-content\/uploads\/2021\/08\/00000001-3.png\" alt=\"\" width=\"497\" height=\"634\" srcset=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/00000001-3.png 497w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/00000001-3-235x300.png 235w\" sizes=\"auto, (max-width: 497px) 100vw, 497px\" \/><\/p>\n<p>Selecione com o bot\u00e3o direito do mouse o App que deseja coloc\u00e1-lo para executar ao fazer login e<\/p>\n<p>marque a op\u00e7\u00e3o &#8221; Iniciar app ao fazer login &#8221;<\/p>\n<p>Pronto, ao fazer o pr\u00f3ximo login em seu computador este App ir\u00e1 iniciar automaticamente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16451 size-medium\" src=\"https:\/\/soloweb.com.br\/blog1\/wp-content\/uploads\/2021\/08\/00000001-4-300x101.png\" alt=\"\" width=\"300\" height=\"101\" srcset=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/00000001-4-300x101.png 300w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/00000001-4-1024x344.png 1024w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/00000001-4-768x258.png 768w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/00000001-4.png 1350w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Note que as PWAs permitem abrir em uma janela a parte semelhante a aplicativos nativos sem a barra de navega\u00e7\u00e3o do browser\/navegador.<\/p>\n<p>Esperamos que tenha gostado desta dica, siga-nos nas redes sociais estamos sempre postando dicas de performance, seguran\u00e7a, ferramentas entre outras.<\/p>\n<h3><strong>E caso deseje ter ou converter seu site para uma PWA, entre em contato conosco, desenvolvemos solu\u00e7\u00f5es personalizadas, sites, sistemas, lojas virtuais e muito mais, al\u00e9m de oferecer os melhores servidores dedicados e VPS com o menor pre\u00e7o do Brasil. Acesse: <a href=\"https:\/\/soloweb.com.br\">www.soloweb.com.br<\/a><\/strong><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Inicie aplica\u00e7\u00f5es PWA ou Progressive Web App automaticamente ap\u00f3s realizar login no Sistema Operacional. Essa capacidade est\u00e1 dispon\u00edvel em muitos<\/p>\n","protected":false},"author":4,"featured_media":16445,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":""},"categories":[114,54],"tags":[112],"class_list":["post-16444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas","category-tutoriais","tag-pwa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Iniciar PWAs automaticamente ap\u00f3s login do Sistema Operacional - SOLOWEB Tecnologia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soloweb.com.br\/blog\/2021\/08\/04\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iniciar PWAs automaticamente ap\u00f3s login do Sistema Operacional - SOLOWEB Tecnologia\" \/>\n<meta property=\"og:description\" content=\"Inicie aplica\u00e7\u00f5es PWA ou Progressive Web App automaticamente ap\u00f3s realizar login no Sistema Operacional. Essa capacidade est\u00e1 dispon\u00edvel em muitos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soloweb.com.br\/blog\/2021\/08\/04\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\/\" \/>\n<meta property=\"og:site_name\" content=\"SOLOWEB Tecnologia\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-05T01:43:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-05-at-00.53.15.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"787\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carlos Rolim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carlos Rolim\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2021\\\/08\\\/04\\\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2021\\\/08\\\/04\\\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\\\/\"},\"author\":{\"name\":\"Carlos Rolim\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/667b825ada5c33664324f9462e7e4f0e\"},\"headline\":\"Iniciar PWAs automaticamente ap\u00f3s login do Sistema Operacional\",\"datePublished\":\"2021-08-05T01:43:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2021\\\/08\\\/04\\\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\\\/\"},\"wordCount\":607,\"publisher\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2021\\\/08\\\/04\\\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/WhatsApp-Image-2021-08-05-at-00.53.15.jpeg\",\"keywords\":[\"pwa\"],\"articleSection\":[\"Dicas\",\"Tutoriais\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2021\\\/08\\\/04\\\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\\\/\",\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2021\\\/08\\\/04\\\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\\\/\",\"name\":\"Iniciar PWAs automaticamente ap\u00f3s login do Sistema Operacional - SOLOWEB Tecnologia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2021\\\/08\\\/04\\\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2021\\\/08\\\/04\\\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/WhatsApp-Image-2021-08-05-at-00.53.15.jpeg\",\"datePublished\":\"2021-08-05T01:43:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2021\\\/08\\\/04\\\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2021\\\/08\\\/04\\\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2021\\\/08\\\/04\\\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/WhatsApp-Image-2021-08-05-at-00.53.15.jpeg\",\"contentUrl\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/WhatsApp-Image-2021-08-05-at-00.53.15.jpeg\",\"width\":940,\"height\":787},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2021\\\/08\\\/04\\\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Iniciar PWAs automaticamente ap\u00f3s login do Sistema Operacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/\",\"name\":\"SOLOWEB Tecnologia\",\"description\":\"SOLOWEB Tecnologia\",\"publisher\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#organization\",\"name\":\"SOLOWEB Tecnologia\",\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-solo.png\",\"contentUrl\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-solo.png\",\"width\":341,\"height\":94,\"caption\":\"SOLOWEB Tecnologia\"},\"image\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/667b825ada5c33664324f9462e7e4f0e\",\"name\":\"Carlos Rolim\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar_user_4_1674993909-96x96.png\",\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar_user_4_1674993909-96x96.png\",\"contentUrl\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar_user_4_1674993909-96x96.png\",\"caption\":\"Carlos Rolim\"},\"sameAs\":[\"http:\\\/\\\/carlosrolim.com\"],\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/author\\\/carlos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Iniciar PWAs automaticamente ap\u00f3s login do Sistema Operacional - SOLOWEB Tecnologia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soloweb.com.br\/blog\/2021\/08\/04\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\/","og_locale":"pt_BR","og_type":"article","og_title":"Iniciar PWAs automaticamente ap\u00f3s login do Sistema Operacional - SOLOWEB Tecnologia","og_description":"Inicie aplica\u00e7\u00f5es PWA ou Progressive Web App automaticamente ap\u00f3s realizar login no Sistema Operacional. Essa capacidade est\u00e1 dispon\u00edvel em muitos","og_url":"https:\/\/soloweb.com.br\/blog\/2021\/08\/04\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\/","og_site_name":"SOLOWEB Tecnologia","article_published_time":"2021-08-05T01:43:45+00:00","og_image":[{"width":940,"height":787,"url":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-05-at-00.53.15.jpeg","type":"image\/jpeg"}],"author":"Carlos Rolim","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carlos Rolim","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/soloweb.com.br\/blog\/2021\/08\/04\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\/#article","isPartOf":{"@id":"https:\/\/soloweb.com.br\/blog\/2021\/08\/04\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\/"},"author":{"name":"Carlos Rolim","@id":"https:\/\/soloweb.com.br\/blog\/#\/schema\/person\/667b825ada5c33664324f9462e7e4f0e"},"headline":"Iniciar PWAs automaticamente ap\u00f3s login do Sistema Operacional","datePublished":"2021-08-05T01:43:45+00:00","mainEntityOfPage":{"@id":"https:\/\/soloweb.com.br\/blog\/2021\/08\/04\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\/"},"wordCount":607,"publisher":{"@id":"https:\/\/soloweb.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/soloweb.com.br\/blog\/2021\/08\/04\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\/#primaryimage"},"thumbnailUrl":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-05-at-00.53.15.jpeg","keywords":["pwa"],"articleSection":["Dicas","Tutoriais"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/soloweb.com.br\/blog\/2021\/08\/04\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\/","url":"https:\/\/soloweb.com.br\/blog\/2021\/08\/04\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\/","name":"Iniciar PWAs automaticamente ap\u00f3s login do Sistema Operacional - SOLOWEB Tecnologia","isPartOf":{"@id":"https:\/\/soloweb.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soloweb.com.br\/blog\/2021\/08\/04\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\/#primaryimage"},"image":{"@id":"https:\/\/soloweb.com.br\/blog\/2021\/08\/04\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\/#primaryimage"},"thumbnailUrl":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-05-at-00.53.15.jpeg","datePublished":"2021-08-05T01:43:45+00:00","breadcrumb":{"@id":"https:\/\/soloweb.com.br\/blog\/2021\/08\/04\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soloweb.com.br\/blog\/2021\/08\/04\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/soloweb.com.br\/blog\/2021\/08\/04\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\/#primaryimage","url":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-05-at-00.53.15.jpeg","contentUrl":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-05-at-00.53.15.jpeg","width":940,"height":787},{"@type":"BreadcrumbList","@id":"https:\/\/soloweb.com.br\/blog\/2021\/08\/04\/iniciar-pwas-automaticamente-no-login-do-sistema-operacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/soloweb.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Iniciar PWAs automaticamente ap\u00f3s login do Sistema Operacional"}]},{"@type":"WebSite","@id":"https:\/\/soloweb.com.br\/blog\/#website","url":"https:\/\/soloweb.com.br\/blog\/","name":"SOLOWEB Tecnologia","description":"SOLOWEB Tecnologia","publisher":{"@id":"https:\/\/soloweb.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soloweb.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/soloweb.com.br\/blog\/#organization","name":"SOLOWEB Tecnologia","url":"https:\/\/soloweb.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/soloweb.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/04\/cropped-solo.png","contentUrl":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/04\/cropped-solo.png","width":341,"height":94,"caption":"SOLOWEB Tecnologia"},"image":{"@id":"https:\/\/soloweb.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/soloweb.com.br\/blog\/#\/schema\/person\/667b825ada5c33664324f9462e7e4f0e","name":"Carlos Rolim","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2023\/01\/avatar_user_4_1674993909-96x96.png","url":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2023\/01\/avatar_user_4_1674993909-96x96.png","contentUrl":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2023\/01\/avatar_user_4_1674993909-96x96.png","caption":"Carlos Rolim"},"sameAs":["http:\/\/carlosrolim.com"],"url":"https:\/\/soloweb.com.br\/blog\/author\/carlos\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/posts\/16444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/comments?post=16444"}],"version-history":[{"count":0,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/posts\/16444\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/media\/16445"}],"wp:attachment":[{"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/media?parent=16444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/categories?post=16444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/tags?post=16444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}