{"id":17345,"date":"2022-11-24T11:34:00","date_gmt":"2022-11-24T11:34:00","guid":{"rendered":"https:\/\/soloweb.com.br\/blog\/?p=17345"},"modified":"2023-03-14T14:09:41","modified_gmt":"2023-03-14T14:09:41","slug":"como-gerenciar-sua-revenda-no-cwp-control-web-panel","status":"publish","type":"post","link":"https:\/\/soloweb.com.br\/blog\/2022\/11\/24\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\/","title":{"rendered":"Como gerenciar sua revenda no CWP (Control Web Panel)"},"content":{"rendered":"\n<p>Na dica de hoje vamos ensinar como gerenciar sua revenda no CWP, vamos ensinar como criar contas, como acessa-las atrav\u00e9s do seu painel, como criar pacotes entre outros.<\/p>\n\n\n\n<p><strong>Precisando de uma hospedagem de site ou de um servidor personalizado, seja para ambiente de desenvolvimento ou de produ\u00e7\u00e3o para seu site, ou sistema? E com um suporte de especialistas, que ti, ajudam a resolver os problemas o mais r\u00e1pido poss\u00edvel? A\u00a0<a href=\"https:\/\/soloweb.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">SoloWeb<\/a>\u00a0tem o prazer em ti, ajudar com isso. Entre em contato conosco e fa\u00e7a uma cota\u00e7\u00e3o agora mesmo, acesse:\u00a0<a href=\"https:\/\/soloweb.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.soloweb.com.br<\/a>.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-soloweb-tecnologia wp-block-embed-soloweb-tecnologia\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"iPvWeb9I8u\"><a href=\"https:\/\/soloweb.com.br\/blog\/2020\/08\/19\/como-resolver-o-problema-de-spam-no-cwp\/\">Como resolver o problema de spam no CWP<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Como resolver o problema de spam no CWP&#8221; &#8212; SOLOWEB Tecnologia\" src=\"https:\/\/soloweb.com.br\/blog\/2020\/08\/19\/como-resolver-o-problema-de-spam-no-cwp\/embed\/#?secret=2QrWtXnj1V#?secret=iPvWeb9I8u\" data-secret=\"iPvWeb9I8u\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\">Veja tamb\u00e9m esta dica&#8230;<\/figcaption><\/figure>\n\n\n\n<p>Vamos \u00e0 dica de hoje.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Passo 1<\/strong><\/h4>\n\n\n\n<p>Acesse sua revenda atrav\u00e9s do link https:\/\/cpanel.dominio.com.br ou servidor.com.br:2083, o CWP utiliza a mesma porta de administra\u00e7\u00e3o do cPanel.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"529\" src=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-10-25-50-1024x529.png\" alt=\"\" class=\"wp-image-17346\" srcset=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-10-25-50-1024x529.png 1024w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-10-25-50-300x155.png 300w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-10-25-50-768x397.png 768w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-10-25-50-150x78.png 150w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-10-25-50.png 1279w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Interface inicial do CWP<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Passo 2<\/strong><\/h4>\n\n\n\n<p>Ap\u00f3s acessar clique em Revendedor &gt; Gerenciar(Lembre de configurar seu painel para linguagem em portugu\u00eas que fica na margem superior direita s\u00f3 \u00e9 clicar na bandeira e escolher Portugu\u00eas &#8211; Portugal).  Pronto agora voc\u00ea estar\u00e1 no painel de gerenciamento de revenda.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"515\" src=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-10-32-15-1024x515.png\" alt=\"\" class=\"wp-image-17347\" srcset=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-10-32-15-1024x515.png 1024w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-10-32-15-300x151.png 300w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-10-32-15-768x386.png 768w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-10-32-15-150x75.png 150w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-10-32-15.png 1279w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Painel de revenda<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Passo 3<\/strong><\/h4>\n\n\n\n<p>Vamos primeiro criar os pacotes da revenda antes de criar as contas, acesse a guia &#8220;Pacotes&#8221; e clique no bot\u00e3o azul &#8220;Adicionar novo pacote&#8221;, uma serie de op\u00e7\u00f5es ir\u00e3o aparecer, mas fique tranquilo praticamente voc\u00ea poder\u00e1 padronizar a maioria.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"401\" data-id=\"17349\" src=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-11-16-00-1-1024x401.png\" alt=\"\" class=\"wp-image-17349\" srcset=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-11-16-00-1-1024x401.png 1024w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-11-16-00-1-300x117.png 300w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-11-16-00-1-768x301.png 768w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-11-16-00-1-150x59.png 150w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-11-16-00-1.png 1111w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Lista de Pacotes<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"612\" data-id=\"17350\" src=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-11-16-15-1024x612.png\" alt=\"\" class=\"wp-image-17350\" srcset=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-11-16-15-1024x612.png 1024w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-11-16-15-300x179.png 300w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-11-16-15-768x459.png 768w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-11-16-15-150x90.png 150w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-11-16-15.png 1112w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cria\u00e7\u00e3o dos pacotes<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p>Para criar o pacotes para seus clientes voc\u00ea dever\u00e1 preencher com os seguintes dados:<\/p>\n\n\n\n<p><strong>Nome do pacote: <\/strong>Aqui voc\u00ea preenche com o nome que desejar usar exemplo Pacote-B\u00e1sico.<strong><br>Quota de disco: <\/strong>Aqui \u00e9 a quantidade de espa\u00e7o em disco que o cliente utilizar\u00e1 em sua revenda ,valor aqui \u00e9 em Megabyte.<strong><br>Largura de banda:  <\/strong>Aqui ir\u00e1 determinar a quantidade de megas navegados o quanto seu site possu\u00edra de tr\u00e1fego mensal.<strong><br>Contas FTP: <\/strong>Aqui ser\u00e1 indicado a quantidade de contas ftp poder\u00e1 ser criada neste pacote. <strong><br>Contas de e-mail:<\/strong> Aqui ser\u00e1 indicado a quantidade de contas de e-mail poder\u00e1 ser criada neste pacote.<strong><br>Listas de Email:<\/strong> Aqui ser\u00e1 indicado a quantidade de redirecionamentos de e-mail voc\u00ea poder\u00e1 criar neste pacote.<strong><br>Bancos de dados:<\/strong> Aqui ser\u00e1 indicado a quantidade de base de dados poder\u00e1 criar(Obs.: n\u00e3o h\u00e1 limita\u00e7\u00e3o para cria\u00e7\u00e3o de usu\u00e1rios para banco de dados).<strong><br>Subdom\u00ednios: <\/strong>Aqui ser\u00e1 indicado quantos subdom\u00ednios poder\u00e3o ser criado neste pacote.<strong><br>Dom\u00ednios Estacionados:<\/strong> Aqui ser\u00e1 indicado quantos dom\u00ednios estacionados poder\u00e3o ser criado neste pacote(Obs.: este recurso \u00e9 desativado no painel por padr\u00e3o).<strong><br>Dom\u00ednios Adicionais:<\/strong> Aqui ser\u00e1 indicado quantos dom\u00ednios estacionados poder\u00e3o ser criado neste pacote.<strong><br>E-mails por hora: <\/strong>Essa op\u00e7\u00e3o n\u00e3o ir\u00e1 diferenciar para quem possui plano de revenda pois a configura\u00e7\u00e3o de envio de e-mail por horas \u00e9 global no servidor(o padr\u00e3o do nosso servidor \u00e9 de 250 e-mail&#8217;S por hora, para valores maiores consulte nossos <a href=\"https:\/\/soloweb.com.br\" target=\"_blank\" rel=\"noreferrer noopener\">planos dedicados<\/a>).<strong><br><\/strong>Esses 3 \u00faltimos pode  colocar valores padr\u00e3o como 0 s\u00e3o recursos para dedicados nos quais futuramente estaremos disponibilizando nas revendas:<strong> &#8220;Editar regras para o dom\u00ednio&#8221;, &#8220;Carregando o editor de regras para&#8221; e &#8220;Editor B\u00e1sico&#8221;.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"379\" src=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-18-07-1024x379.png\" alt=\"\" class=\"wp-image-17351\" srcset=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-18-07-1024x379.png 1024w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-18-07-300x111.png 300w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-18-07-768x284.png 768w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-18-07-150x55.png 150w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-18-07.png 1111w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Pacote criado<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Passo 4<\/strong><\/h4>\n\n\n\n<p>Agora com os pacotes criados, vamos personalizar a revenda com sua marca, v\u00e1 na op\u00e7\u00e3o Branding e preencha os campos desta op\u00e7\u00e3o com informa\u00e7\u00f5es sobre sua empresa de revenda:<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"450\" src=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-39-18-1024x450.png\" alt=\"\" class=\"wp-image-17352\" srcset=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-39-18-1024x450.png 1024w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-39-18-300x132.png 300w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-39-18-768x337.png 768w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-39-18-150x66.png 150w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-39-18.png 1111w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Painel Branding(Marca)<\/figcaption><\/figure>\n\n\n\n<p>Aqui voc\u00ea poder\u00e1 inserir sua logo, uma mensagem de rodap\u00e9 que ficar\u00e1 no painel o titulo que ficar\u00e1 na descri\u00e7\u00e3o da aba e e-mail para backup do nome e do endere\u00e7o(importante configurar para seus clientes receberem notifica\u00e7\u00f5es do painel a partir do seu e-mail e n\u00e3o o padr\u00e3o do servidor).<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"447\" src=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-46-47-1024x447.png\" alt=\"\" class=\"wp-image-17353\" srcset=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-46-47-1024x447.png 1024w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-46-47-300x131.png 300w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-46-47-768x335.png 768w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-46-47-150x66.png 150w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-46-47.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Configura\u00e7\u00e3o Branding(Marca)<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Passo 5<\/strong><\/h4>\n\n\n\n<p>A guia Caracter\u00edsticas \u00e9 uma guia opcional para caso voc\u00ea deseja personalizar mais ainda as op\u00e7\u00f5es de uma revenda, por exemplo, certos pacotes poder\u00e1 s\u00f3 ter acesso a e-mails, outros pacotes n\u00e3o poder\u00e3o modificar DNS&#8217;s, ETC. <\/p>\n\n\n\n<p>Ent\u00e3o essa configura\u00e7\u00e3o \u00e9 bem simples basta clicar em &#8220;Adicionar nova configura\u00e7\u00e3o&#8221; selecionar o pacote que deseja  configurar e adicionar cada recurso que deseja mostrar no painel:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"555\" src=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-50-49-1024x555.png\" alt=\"\" class=\"wp-image-17354\" srcset=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-50-49-1024x555.png 1024w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-50-49-300x163.png 300w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-50-49-768x416.png 768w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-50-49-150x81.png 150w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-50-49.png 1112w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Painel de configura\u00e7\u00e3o de caracter\u00edsticas<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Passo 6<\/strong><\/h4>\n\n\n\n<p>Na aba de configura\u00e7\u00e3o de &#8220;Servidores de nomes&#8221; voc\u00ea vai precisar solicitar a nosso suporte primeiro para criar servidores de nomes personalizados, assim que criar, voc\u00ea poder\u00e1 acessar a aba e informar quais os DNS&#8217;s ser\u00e3o configurados para cada conta criada:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"520\" src=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-55-14-1024x520.png\" alt=\"\" class=\"wp-image-17355\" srcset=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-55-14-1024x520.png 1024w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-55-14-300x152.png 300w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-55-14-768x390.png 768w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-55-14-150x76.png 150w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-12-55-14.png 1107w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Painel de configura\u00e7\u00e3o de servidores de nome<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Passo 7<\/strong><\/h4>\n\n\n\n<p>Com toda essa configura\u00e7\u00e3o feita agora vamos criar as contas, no qual \u00e9 muito simples, basta acessar a guia Contas, la vai esta listada as contas j\u00e1 criadas e poder\u00e1 criar l\u00e1 tamb\u00e9m basta clicar no bot\u00e3o &#8220;+&#8221; e preencher as seguintes infoma\u00e7\u00f5es:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-01-00-1024x536.png\" alt=\"\" class=\"wp-image-17356\" srcset=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-01-00-1024x536.png 1024w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-01-00-300x157.png 300w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-01-00-768x402.png 768w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-01-00-390x205.png 390w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-01-00-150x78.png 150w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-01-00.png 1116w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Adicionar conta<\/figcaption><\/figure>\n\n\n\n<p><strong>Nome do dom\u00ednio<\/strong>: Preencha com o nome do dom\u00ednio do seu cliente sem o www.<\/p>\n\n\n\n<p><strong>Nome do usu\u00e1rio<\/strong>: automaticamente j\u00e1 preencher\u00e1 quando voc\u00ea digitar o nome do dom\u00ednio, se n\u00e3o preencher basta digitar o nome do usu\u00e1rio que deseja.<\/p>\n\n\n\n<p><strong>Senha:<\/strong> recomenda-se utilizar senha de n\u00edvel forte, clique na chave que j\u00e1 ir\u00e1 gerar de forma autom\u00e1tica mas se preferir pode digitar a senha que deseja criar.<\/p>\n\n\n\n<p><strong>Email do administrador:<\/strong> preencha com o e-mail de cadastro do cliente.<\/p>\n\n\n\n<p><strong>Pacote:<\/strong> Selecione o pacote adquirido pelo cliente.<\/p>\n\n\n\n<p>Deixe marcado as duas ultimas op\u00e7\u00f5es e deixe o pacote de idioma padr\u00e3o e pronto s\u00f3 clicar em salvar.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Passo 8<\/strong><\/h4>\n\n\n\n<p>Ap\u00f3s criar sua conta voc\u00ea poder\u00e1 gerencia-la atrav\u00e9s do painel de contas, onde poder\u00e1 suspende-la, ativar ou desativar backup entre outras coisas.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"503\" src=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-33-33-1024x503.png\" alt=\"\" class=\"wp-image-17357\" srcset=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-33-33-1024x503.png 1024w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-33-33-300x147.png 300w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-33-33-768x377.png 768w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-33-33-150x74.png 150w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-33-33.png 1279w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Painel de gerenciamento de contas.<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Passo 9<\/strong><\/h4>\n\n\n\n<p>Das tr\u00eas ultimas guia a mais importante para voc\u00ea utilizar inicialmente \u00e9 a Firewall, caso um dos seus clientes precisar desbloquear ip basta acessar essa guia e colocar o ip do cliente e clicar no bot\u00e3o vermelho &#8220;Remover&#8221;:<\/p>\n\n\n\n<figure class=\"wp-block-image alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"458\" src=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-48-35-1024x458.png\" alt=\"\" class=\"wp-image-17358\" srcset=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-48-35-1024x458.png 1024w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-48-35-300x134.png 300w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-48-35-768x344.png 768w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-48-35-150x67.png 150w, https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/Captura-de-tela-de-2022-11-23-13-48-35.png 1110w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Guia para remover ip bloqueado no firewall.<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>A guia Gerente de API \u00e9 para programadores mais experientes que precisar desenvolver ou integrar API para o CWP.<\/p>\n\n\n\n<p>E o modsecurity apenas vai listar ips ou faixas bloqueadas por este recurso em nosso servidor.<\/p>\n\n\n\n<p>Pronto agora voc\u00ea esta habilitado para gerenciar sua revenda no CWP.<\/p>\n\n\n\n<p>Fique atento as novidades que a <a href=\"http:\/\/www.soloweb.com.br\">SoloWeb<\/a> vem lan\u00e7ando.<\/p>\n\n\n\n<p><em><strong>E lembrando que a&nbsp;<a href=\"https:\/\/soloweb.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">SOLOWEB<\/a>&nbsp;al\u00e9m de oferecer Hospedagem de Sites, Servidores Dedicados, Servidores VPS com o menor custo do Brasil, tamb\u00e9m desenvolve solu\u00e7\u00f5es de software e realiza gerenciamento e monitoramento de servidores para sua empresa, fa\u00e7a uma cota\u00e7\u00e3o sem custo, acesse:&nbsp;<a href=\"https:\/\/soloweb.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.soloweb.com.br<\/a><\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na dica de hoje vamos ensinar como gerenciar sua revenda no CWP, vamos ensinar como criar contas, como acessa-las atrav\u00e9s<\/p>\n","protected":false},"author":5,"featured_media":17363,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":""},"categories":[120,302],"tags":[143,121,115,28,144,38,39,309],"class_list":["post-17345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cwp","category-destaque-principal","tag-centos","tag-cwp","tag-dicas","tag-hospedagem","tag-linux","tag-revenda","tag-site","tag-tutoriais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como gerenciar sua revenda no CWP (Control Web Panel) - SOLOWEB Tecnologia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soloweb.com.br\/blog\/2022\/11\/24\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como gerenciar sua revenda no CWP (Control Web Panel) - SOLOWEB Tecnologia\" \/>\n<meta property=\"og:description\" content=\"Na dica de hoje vamos ensinar como gerenciar sua revenda no CWP, vamos ensinar como criar contas, como acessa-las atrav\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soloweb.com.br\/blog\/2022\/11\/24\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\/\" \/>\n<meta property=\"og:site_name\" content=\"SOLOWEB Tecnologia\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-24T11:34:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-14T14:09:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-08.31.12.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"787\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ademilton Filho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ademilton Filho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/11\\\/24\\\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/11\\\/24\\\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\\\/\"},\"author\":{\"name\":\"Ademilton Filho\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f868b83846c5e132dde12db8492335df\"},\"headline\":\"Como gerenciar sua revenda no CWP (Control Web Panel)\",\"datePublished\":\"2022-11-24T11:34:00+00:00\",\"dateModified\":\"2023-03-14T14:09:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/11\\\/24\\\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\\\/\"},\"wordCount\":1118,\"publisher\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/11\\\/24\\\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WhatsApp-Image-2022-11-24-at-08.31.12.jpeg\",\"keywords\":[\"centos\",\"CWP\",\"dicas\",\"hospedagem\",\"linux\",\"revenda\",\"site\",\"tutoriais\"],\"articleSection\":[\"CWP\",\"Destaque Principal\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/11\\\/24\\\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\\\/\",\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/11\\\/24\\\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\\\/\",\"name\":\"Como gerenciar sua revenda no CWP (Control Web Panel) - SOLOWEB Tecnologia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/11\\\/24\\\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/11\\\/24\\\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WhatsApp-Image-2022-11-24-at-08.31.12.jpeg\",\"datePublished\":\"2022-11-24T11:34:00+00:00\",\"dateModified\":\"2023-03-14T14:09:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/11\\\/24\\\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/11\\\/24\\\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/11\\\/24\\\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WhatsApp-Image-2022-11-24-at-08.31.12.jpeg\",\"contentUrl\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WhatsApp-Image-2022-11-24-at-08.31.12.jpeg\",\"width\":940,\"height\":787},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/11\\\/24\\\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como gerenciar sua revenda no CWP (Control Web Panel)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/\",\"name\":\"SOLOWEB Tecnologia\",\"description\":\"SOLOWEB Tecnologia\",\"publisher\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#organization\",\"name\":\"SOLOWEB Tecnologia\",\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-solo.png\",\"contentUrl\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-solo.png\",\"width\":341,\"height\":94,\"caption\":\"SOLOWEB Tecnologia\"},\"image\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f868b83846c5e132dde12db8492335df\",\"name\":\"Ademilton Filho\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar_user_5_1674994251-96x96.png\",\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar_user_5_1674994251-96x96.png\",\"contentUrl\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar_user_5_1674994251-96x96.png\",\"caption\":\"Ademilton Filho\"},\"sameAs\":[\"http:\\\/\\\/ademiltonsoftware.tk\"],\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/author\\\/ademilton\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como gerenciar sua revenda no CWP (Control Web Panel) - SOLOWEB Tecnologia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soloweb.com.br\/blog\/2022\/11\/24\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\/","og_locale":"pt_BR","og_type":"article","og_title":"Como gerenciar sua revenda no CWP (Control Web Panel) - SOLOWEB Tecnologia","og_description":"Na dica de hoje vamos ensinar como gerenciar sua revenda no CWP, vamos ensinar como criar contas, como acessa-las atrav\u00e9s","og_url":"https:\/\/soloweb.com.br\/blog\/2022\/11\/24\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\/","og_site_name":"SOLOWEB Tecnologia","article_published_time":"2022-11-24T11:34:00+00:00","article_modified_time":"2023-03-14T14:09:41+00:00","og_image":[{"width":940,"height":787,"url":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-08.31.12.jpeg","type":"image\/jpeg"}],"author":"Ademilton Filho","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ademilton Filho","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/soloweb.com.br\/blog\/2022\/11\/24\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\/#article","isPartOf":{"@id":"https:\/\/soloweb.com.br\/blog\/2022\/11\/24\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\/"},"author":{"name":"Ademilton Filho","@id":"https:\/\/soloweb.com.br\/blog\/#\/schema\/person\/f868b83846c5e132dde12db8492335df"},"headline":"Como gerenciar sua revenda no CWP (Control Web Panel)","datePublished":"2022-11-24T11:34:00+00:00","dateModified":"2023-03-14T14:09:41+00:00","mainEntityOfPage":{"@id":"https:\/\/soloweb.com.br\/blog\/2022\/11\/24\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\/"},"wordCount":1118,"publisher":{"@id":"https:\/\/soloweb.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/soloweb.com.br\/blog\/2022\/11\/24\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\/#primaryimage"},"thumbnailUrl":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-08.31.12.jpeg","keywords":["centos","CWP","dicas","hospedagem","linux","revenda","site","tutoriais"],"articleSection":["CWP","Destaque Principal"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/soloweb.com.br\/blog\/2022\/11\/24\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\/","url":"https:\/\/soloweb.com.br\/blog\/2022\/11\/24\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\/","name":"Como gerenciar sua revenda no CWP (Control Web Panel) - SOLOWEB Tecnologia","isPartOf":{"@id":"https:\/\/soloweb.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soloweb.com.br\/blog\/2022\/11\/24\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\/#primaryimage"},"image":{"@id":"https:\/\/soloweb.com.br\/blog\/2022\/11\/24\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\/#primaryimage"},"thumbnailUrl":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-08.31.12.jpeg","datePublished":"2022-11-24T11:34:00+00:00","dateModified":"2023-03-14T14:09:41+00:00","breadcrumb":{"@id":"https:\/\/soloweb.com.br\/blog\/2022\/11\/24\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soloweb.com.br\/blog\/2022\/11\/24\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/soloweb.com.br\/blog\/2022\/11\/24\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\/#primaryimage","url":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-08.31.12.jpeg","contentUrl":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-08.31.12.jpeg","width":940,"height":787},{"@type":"BreadcrumbList","@id":"https:\/\/soloweb.com.br\/blog\/2022\/11\/24\/como-gerenciar-sua-revenda-no-cwp-control-web-panel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/soloweb.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Como gerenciar sua revenda no CWP (Control Web Panel)"}]},{"@type":"WebSite","@id":"https:\/\/soloweb.com.br\/blog\/#website","url":"https:\/\/soloweb.com.br\/blog\/","name":"SOLOWEB Tecnologia","description":"SOLOWEB Tecnologia","publisher":{"@id":"https:\/\/soloweb.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soloweb.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/soloweb.com.br\/blog\/#organization","name":"SOLOWEB Tecnologia","url":"https:\/\/soloweb.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/soloweb.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/04\/cropped-solo.png","contentUrl":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/04\/cropped-solo.png","width":341,"height":94,"caption":"SOLOWEB Tecnologia"},"image":{"@id":"https:\/\/soloweb.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/soloweb.com.br\/blog\/#\/schema\/person\/f868b83846c5e132dde12db8492335df","name":"Ademilton Filho","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2023\/01\/avatar_user_5_1674994251-96x96.png","url":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2023\/01\/avatar_user_5_1674994251-96x96.png","contentUrl":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2023\/01\/avatar_user_5_1674994251-96x96.png","caption":"Ademilton Filho"},"sameAs":["http:\/\/ademiltonsoftware.tk"],"url":"https:\/\/soloweb.com.br\/blog\/author\/ademilton\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/posts\/17345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/comments?post=17345"}],"version-history":[{"count":4,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/posts\/17345\/revisions"}],"predecessor-version":[{"id":17704,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/posts\/17345\/revisions\/17704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/media\/17363"}],"wp:attachment":[{"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/media?parent=17345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/categories?post=17345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/tags?post=17345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}