{"id":17450,"date":"2022-12-19T12:56:32","date_gmt":"2022-12-19T12:56:32","guid":{"rendered":"https:\/\/soloweb.com.br\/blog\/?p=17450"},"modified":"2023-04-02T12:52:58","modified_gmt":"2023-04-02T12:52:58","slug":"como-usar-o-operador-ternario-do-javascript","status":"publish","type":"post","link":"https:\/\/soloweb.com.br\/blog\/2022\/12\/19\/como-usar-o-operador-ternario-do-javascript\/","title":{"rendered":"Como usar o Operador Tern\u00e1rio do JavaScript"},"content":{"rendered":"\n<p>Neste post vamos falar sobre o Operador Tern\u00e1rio em JavaScript.  Discutiremos o que \u00e9 o operador tern\u00e1rio, como \u00e9 usado, quando us\u00e1-lo e como ele se compara com: <em><strong>if\/else, if\/else if\/elsee switch.<\/strong><\/em><\/p>\n\n\n\n<p>O que \u00e9 o Operador Tern\u00e1rio do JavaScript<\/p>\n\n\n\n<p>O operador tern\u00e1rio em JavaScript \u00e9 um operador denotado pelo ponto de interroga\u00e7\u00e3o, <strong><em>?<\/em><\/strong> , que avalia uma express\u00e3o condicional passada antes dele e executa um bloco de c\u00f3digo com base na decis\u00e3o da express\u00e3o condicional. Ele aceita os poss\u00edveis blocos a serem executados como dois outros operandos que v\u00eam depois do <strong><em>?<\/em><\/strong>  operador &#8211; o terceiro separado do segundo por dois pontos, <strong><em>:<\/em><\/strong> . <\/p>\n\n\n\n<p>Sua sintaxe fica assim:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>expressaoCondicional ? retornoSeVerdadeiro : retornoSeFalso ;\n<\/code><\/pre>\n\n\n\n<p>Se a <strong><em>expressaoCondicional<\/em><\/strong>  for avaliada para um valor verdadeiro <strong><em>retornoSeVerdadeiro<\/em><\/strong> \u00e9 executada. Se for avaliado como um valor falso, <strong><em>retornoSeFalso<\/em><\/strong> \u00e9 executado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como usar o operador tern\u00e1rio<\/h2>\n\n\n\n<p>Podemos usar o operador tern\u00e1rio quando precisamos decidir o valor de retorno de uma vari\u00e1vel de duas ou mais op\u00e7\u00f5es com base em uma condi\u00e7\u00e3o que passamos como primeiro operando.&nbsp;O c\u00f3digo abaixo mostra como:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>\nconst estudante = 'Jo\u00e3o';\nconst bemVindoEstudante = estudante ? `Bem vindo, ${estudante}!` : \"Bem Vindo Convidado!\";\n\nconsole.log(bemVindoEstudante); \n\n\/\/ Sa\u00edda:\n\/\/ Bem vindo, Jo\u00e3o!<\/code><\/pre>\n\n\n\n<p>No trecho acima, <strong><em>estudante<\/em><\/strong>  ? \u00e9 avaliada a express\u00e3o antes da <strong><em>?<\/em><\/strong>  como uma condi\u00e7\u00e3o <strong><em>booleana<\/em><\/strong>, perguntando se <strong><em>estudante<\/em><\/strong> \u00e9 verdadeira. Por esse motivo, o operador tern\u00e1rio, <strong>?<\/strong> , tamb\u00e9m \u00e9 chamado de <strong>operador condicional<\/strong>.<\/p>\n\n\n\n<p>O valor dessa express\u00e3o condicional \u00e9 usado para decidir o valor da vari\u00e1vel armazenada, <strong><em>bemVindoEstudante<\/em><\/strong>. Se o operando condicional for avaliado como um valor verdadeiro, o segundo operando, ou seja, o valor antes dos dois pontos, <strong>:<\/strong> , \u00e9 retornado para <strong><em>bemVindoEstudante<\/em><\/strong>. Se for avaliado como falso, o terceiro operando, ou seja, aquele ap\u00f3s o <strong>:<\/strong> \u00e9 retornado.<\/p>\n\n\n\n<p>Em JavaScript, os valores falsos incluem <strong><em>false , 0 , -0 , &#8220;&#8221; , null undefined e NaN<\/em><\/strong> Todos os outros valores s\u00e3o considerados verdadeiros.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quando usar<\/h2>\n\n\n\n<p>O caso de uso mais comum do operador tern\u00e1rio \u00e9 quando h\u00e1 apenas dois resultados poss\u00edveis, ou seja, como uma alternativa abreviada da if\/elseconstru\u00e7\u00e3o. O uso do operador tern\u00e1rio torna o c\u00f3digo mais leg\u00edvel e geralmente ocupa menos linhas.<\/p>\n\n\n\n<p>Como no exemplo acima, pode ser usado para retornar o valor de uma vari\u00e1vel diretamente.<\/p>\n\n\n\n<p>Tamb\u00e9m pode ser usado quando precisamos retornar um valor de uma fun\u00e7\u00e3o:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>\/\/ Com if\/else\n\nconst bemVindoEstudante = student =&gt; {\n  if (student) {\n    return `Bem vindo, ${student.name}!`;\n  } else {\n    return \"Bem vindo, convidado!\";\n  };\n};\n\nconsole.log(bemVindoEstudante({ name: 'Carlos' })); \n\/\/ Sa\u00edda:\n\/\/ Bem vindo, Carlos!\n\nconsole.log(bemVindoEstudante()); \n\/\/ Sa\u00edda\n\/\/ Bem vindo, convidado!!\n\n\n\/\/ Com operador tern\u00e1rio\nconst bemVindoEstudante = student =&gt; student ? `Bem vindo, ${student.name}!` : \"Bem vindo, convidado!\";\n\nconsole.log(bemVindoEstudante({ name: 'Carlos' })); \n\/\/ Sa\u00edda:\n\/\/ Bem vindo, Carlos!\n\nconsole.log(bemVindoEstudante()); \n\/\/ Sa\u00edda:\n\/\/ Bem vindo, convidado!\n<\/code><\/pre>\n\n\n\n<p>Como podemos ver, o operador tern\u00e1rio simplifica o c\u00f3digo para uma linha.&nbsp;Tornou o c\u00f3digo mais leg\u00edvel e a l\u00f3gica f\u00e1cil de seguir.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Operador tern\u00e1rio encadeado<\/h2>\n\n\n\n<p>Podemos encadear operadores tern\u00e1rios para emular uma <strong><em>if\/else if\/else<\/em><\/strong> ou um <strong><em>switch:<\/em><\/strong><\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>\/\/ Com if\/else if\/else\nconst grade = mark =&gt; {\n  if (mark &gt; 100) {\n    return;\n  } else if (mark &gt; 80) {\n    return 'A';\n  } else if (mark &gt; 70) {\n    return 'B';\n  } else if (mark &gt; 60) {\n    return 'C';\n  } else if (mark &gt; 50) {\n    return 'D';\n  } else {\n    return 'F';\n  };\n};\n\nconsole.log(grade(100)); \n\/\/ Sa\u00edda:\n\/\/ A\n\nconsole.log(grade(1000)); \n\/\/ Sa\u00edda\n\/\/ undefined\n\nconsole.log(grade(10)); \n\/\/ Sa\u00edda\n\/\/ F\n\n\/\/ Com operadores tern\u00e1rios encadeados\nconst grade = mark =&gt; mark &gt; 100 ? undefined\n                      : mark &gt; 80 ? 'A'\n                      : mark &gt; 70 ? 'B'\n                      : mark &gt; 60 ? 'C'\n                      : mark &gt; 50 ? 'D'\n                      : 'F';\n\nconsole.log(grade(100)); \n\/\/ Sa\u00edda:\n\/\/ A\n\nconsole.log(grade(1000)); \n\/\/ Sa\u00edda:\n\/\/ undefined\n\nconsole.log(grade(10)); \n\/\/ Sa\u00edda:\n\/\/ F<\/code><\/pre>\n\n\n\n<p>Aqui, encadeamos o operador condicional no terceiro operando do operador tern\u00e1rio em cada n\u00edvel.<\/p>\n\n\n\n<p>Muitos desenvolvedores n\u00e3o preferem operadores tern\u00e1rios aninhados como este porque v\u00e1rias verifica\u00e7\u00f5es condicionais prejudicam a legibilidade, em vez de melhor\u00e1-la. Ao contr\u00e1rio do encadeamento de operadores tern\u00e1rios, o uso de instru\u00e7\u00f5es simples <strong><em>if\/else if\/else<\/em><\/strong> ou simples <strong><em>switch<\/em><\/strong> \u00e9 recomendado quando h\u00e1 v\u00e1rias bifurca\u00e7\u00f5es em um fluxo de controle.<\/p>\n\n\n\n<p>Neste artigo, exploramos o uso do operador tern\u00e1rio em JavaScript. Vimos dois casos comuns que melhoram a legibilidade do c\u00f3digo, um envolvendo uma vari\u00e1vel e o outro uma express\u00e3o de fun\u00e7\u00e3o que retorna um valor com base na avalia\u00e7\u00e3o de uma express\u00e3o condicional dentro de uma fun\u00e7\u00e3o.<\/p>\n\n\n\n<p>Os operadores tern\u00e1rios podem ser encadeados para emular <strong><em>if\/else if\/else e switchr<\/em><\/strong>, mas a maneira recomendada \u00e9 manter as constru\u00e7\u00f5es posteriores porque o encadeamento de v\u00e1rios operadores tern\u00e1rios \u00e9 contraproducente em termos de legibilidade.<\/p>\n\n\n\n<p>Esperamos ter ajudado com mais esta dica, e siga nos, nas redes sociais para mais tutoriais&nbsp;<a href=\"https:\/\/soloweb.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.soloweb.com.br<\/a>.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste post vamos falar sobre o Operador Tern\u00e1rio em JavaScript. Discutiremos o que \u00e9 o operador tern\u00e1rio, como \u00e9 usado,<\/p>\n","protected":false},"author":4,"featured_media":17453,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":""},"categories":[302,240],"tags":[224,346,348],"class_list":["post-17450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque-principal","category-javascript","tag-javascript","tag-operador","tag-ternario-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como usar o Operador Tern\u00e1rio do JavaScript - SOLOWEB Tecnologia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soloweb.com.br\/blog\/2022\/12\/19\/como-usar-o-operador-ternario-do-javascript\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como usar o Operador Tern\u00e1rio do JavaScript - SOLOWEB Tecnologia\" \/>\n<meta property=\"og:description\" content=\"Neste post vamos falar sobre o Operador Tern\u00e1rio em JavaScript. Discutiremos o que \u00e9 o operador tern\u00e1rio, como \u00e9 usado,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soloweb.com.br\/blog\/2022\/12\/19\/como-usar-o-operador-ternario-do-javascript\/\" \/>\n<meta property=\"og:site_name\" content=\"SOLOWEB Tecnologia\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-19T12:56:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-02T12:52:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-19-at-09.51.42.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"787\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carlos Rolim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carlos Rolim\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/12\\\/19\\\/como-usar-o-operador-ternario-do-javascript\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/12\\\/19\\\/como-usar-o-operador-ternario-do-javascript\\\/\"},\"author\":{\"name\":\"Carlos Rolim\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/b10ff5bc260b411c2d82b19fad8ae3f1\"},\"headline\":\"Como usar o Operador Tern\u00e1rio do JavaScript\",\"datePublished\":\"2022-12-19T12:56:32+00:00\",\"dateModified\":\"2023-04-02T12:52:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/12\\\/19\\\/como-usar-o-operador-ternario-do-javascript\\\/\"},\"wordCount\":612,\"publisher\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/12\\\/19\\\/como-usar-o-operador-ternario-do-javascript\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/WhatsApp-Image-2022-12-19-at-09.51.42.jpeg\",\"keywords\":[\"javascript\",\"operador\",\"tern\u00e1rio\"],\"articleSection\":[\"Destaque Principal\",\"JavaScript\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/12\\\/19\\\/como-usar-o-operador-ternario-do-javascript\\\/\",\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/12\\\/19\\\/como-usar-o-operador-ternario-do-javascript\\\/\",\"name\":\"Como usar o Operador Tern\u00e1rio do JavaScript - SOLOWEB Tecnologia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/12\\\/19\\\/como-usar-o-operador-ternario-do-javascript\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/12\\\/19\\\/como-usar-o-operador-ternario-do-javascript\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/WhatsApp-Image-2022-12-19-at-09.51.42.jpeg\",\"datePublished\":\"2022-12-19T12:56:32+00:00\",\"dateModified\":\"2023-04-02T12:52:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/12\\\/19\\\/como-usar-o-operador-ternario-do-javascript\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/12\\\/19\\\/como-usar-o-operador-ternario-do-javascript\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/12\\\/19\\\/como-usar-o-operador-ternario-do-javascript\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/WhatsApp-Image-2022-12-19-at-09.51.42.jpeg\",\"contentUrl\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/WhatsApp-Image-2022-12-19-at-09.51.42.jpeg\",\"width\":940,\"height\":787},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/2022\\\/12\\\/19\\\/como-usar-o-operador-ternario-do-javascript\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como usar o Operador Tern\u00e1rio do JavaScript\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/\",\"name\":\"SOLOWEB Tecnologia\",\"description\":\"SOLOWEB Tecnologia\",\"publisher\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#organization\",\"name\":\"SOLOWEB Tecnologia\",\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-solo.png\",\"contentUrl\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-solo.png\",\"width\":341,\"height\":94,\"caption\":\"SOLOWEB Tecnologia\"},\"image\":{\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/b10ff5bc260b411c2d82b19fad8ae3f1\",\"name\":\"Carlos Rolim\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar_user_4_1674993909-96x96.png\",\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar_user_4_1674993909-96x96.png\",\"contentUrl\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar_user_4_1674993909-96x96.png\",\"caption\":\"Carlos Rolim\"},\"sameAs\":[\"http:\\\/\\\/carlosrolim.com\"],\"url\":\"https:\\\/\\\/soloweb.com.br\\\/blog\\\/author\\\/carlos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como usar o Operador Tern\u00e1rio do JavaScript - SOLOWEB Tecnologia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soloweb.com.br\/blog\/2022\/12\/19\/como-usar-o-operador-ternario-do-javascript\/","og_locale":"pt_BR","og_type":"article","og_title":"Como usar o Operador Tern\u00e1rio do JavaScript - SOLOWEB Tecnologia","og_description":"Neste post vamos falar sobre o Operador Tern\u00e1rio em JavaScript. Discutiremos o que \u00e9 o operador tern\u00e1rio, como \u00e9 usado,","og_url":"https:\/\/soloweb.com.br\/blog\/2022\/12\/19\/como-usar-o-operador-ternario-do-javascript\/","og_site_name":"SOLOWEB Tecnologia","article_published_time":"2022-12-19T12:56:32+00:00","article_modified_time":"2023-04-02T12:52:58+00:00","og_image":[{"width":940,"height":787,"url":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-19-at-09.51.42.jpeg","type":"image\/jpeg"}],"author":"Carlos Rolim","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carlos Rolim","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/soloweb.com.br\/blog\/2022\/12\/19\/como-usar-o-operador-ternario-do-javascript\/#article","isPartOf":{"@id":"https:\/\/soloweb.com.br\/blog\/2022\/12\/19\/como-usar-o-operador-ternario-do-javascript\/"},"author":{"name":"Carlos Rolim","@id":"https:\/\/soloweb.com.br\/blog\/#\/schema\/person\/b10ff5bc260b411c2d82b19fad8ae3f1"},"headline":"Como usar o Operador Tern\u00e1rio do JavaScript","datePublished":"2022-12-19T12:56:32+00:00","dateModified":"2023-04-02T12:52:58+00:00","mainEntityOfPage":{"@id":"https:\/\/soloweb.com.br\/blog\/2022\/12\/19\/como-usar-o-operador-ternario-do-javascript\/"},"wordCount":612,"publisher":{"@id":"https:\/\/soloweb.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/soloweb.com.br\/blog\/2022\/12\/19\/como-usar-o-operador-ternario-do-javascript\/#primaryimage"},"thumbnailUrl":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-19-at-09.51.42.jpeg","keywords":["javascript","operador","tern\u00e1rio"],"articleSection":["Destaque Principal","JavaScript"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/soloweb.com.br\/blog\/2022\/12\/19\/como-usar-o-operador-ternario-do-javascript\/","url":"https:\/\/soloweb.com.br\/blog\/2022\/12\/19\/como-usar-o-operador-ternario-do-javascript\/","name":"Como usar o Operador Tern\u00e1rio do JavaScript - SOLOWEB Tecnologia","isPartOf":{"@id":"https:\/\/soloweb.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soloweb.com.br\/blog\/2022\/12\/19\/como-usar-o-operador-ternario-do-javascript\/#primaryimage"},"image":{"@id":"https:\/\/soloweb.com.br\/blog\/2022\/12\/19\/como-usar-o-operador-ternario-do-javascript\/#primaryimage"},"thumbnailUrl":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-19-at-09.51.42.jpeg","datePublished":"2022-12-19T12:56:32+00:00","dateModified":"2023-04-02T12:52:58+00:00","breadcrumb":{"@id":"https:\/\/soloweb.com.br\/blog\/2022\/12\/19\/como-usar-o-operador-ternario-do-javascript\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soloweb.com.br\/blog\/2022\/12\/19\/como-usar-o-operador-ternario-do-javascript\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/soloweb.com.br\/blog\/2022\/12\/19\/como-usar-o-operador-ternario-do-javascript\/#primaryimage","url":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-19-at-09.51.42.jpeg","contentUrl":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-19-at-09.51.42.jpeg","width":940,"height":787},{"@type":"BreadcrumbList","@id":"https:\/\/soloweb.com.br\/blog\/2022\/12\/19\/como-usar-o-operador-ternario-do-javascript\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/soloweb.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Como usar o Operador Tern\u00e1rio do JavaScript"}]},{"@type":"WebSite","@id":"https:\/\/soloweb.com.br\/blog\/#website","url":"https:\/\/soloweb.com.br\/blog\/","name":"SOLOWEB Tecnologia","description":"SOLOWEB Tecnologia","publisher":{"@id":"https:\/\/soloweb.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soloweb.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/soloweb.com.br\/blog\/#organization","name":"SOLOWEB Tecnologia","url":"https:\/\/soloweb.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/soloweb.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/04\/cropped-solo.png","contentUrl":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2022\/04\/cropped-solo.png","width":341,"height":94,"caption":"SOLOWEB Tecnologia"},"image":{"@id":"https:\/\/soloweb.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/soloweb.com.br\/blog\/#\/schema\/person\/b10ff5bc260b411c2d82b19fad8ae3f1","name":"Carlos Rolim","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2023\/01\/avatar_user_4_1674993909-96x96.png","url":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2023\/01\/avatar_user_4_1674993909-96x96.png","contentUrl":"https:\/\/soloweb.com.br\/blog\/wp-content\/uploads\/2023\/01\/avatar_user_4_1674993909-96x96.png","caption":"Carlos Rolim"},"sameAs":["http:\/\/carlosrolim.com"],"url":"https:\/\/soloweb.com.br\/blog\/author\/carlos\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/posts\/17450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/comments?post=17450"}],"version-history":[{"count":4,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/posts\/17450\/revisions"}],"predecessor-version":[{"id":17814,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/posts\/17450\/revisions\/17814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/media\/17453"}],"wp:attachment":[{"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/media?parent=17450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/categories?post=17450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soloweb.com.br\/blog\/wp-json\/wp\/v2\/tags?post=17450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}